{"id":712,"count":1,"description":"","link":"https:\/\/wormholeriders.net\/Drama\/category\/interviews\/2013-robin-dunne-repetitive-strain-injury-november-30\/","name":"2013 - Robin Dunne Repetitive Strain Injury November 30","slug":"2013-robin-dunne-repetitive-strain-injury-november-30","taxonomy":"category","parent":285,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2013 - Robin Dunne Repetitive Strain Injury November 30 Archives - WormholeRiders Dedicated to Drama<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wormholeriders.net\/Drama\/category\/interviews\/2013-robin-dunne-repetitive-strain-injury-november-30\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2013 - Robin Dunne Repetitive Strain Injury November 30 Archives - WormholeRiders Dedicated to Drama\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wormholeriders.net\/Drama\/category\/interviews\/2013-robin-dunne-repetitive-strain-injury-november-30\/\" \/>\n<meta property=\"og:site_name\" content=\"WormholeRiders Dedicated to Drama\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/wormholeriders.net\\\/Drama\\\/category\\\/interviews\\\/2013-robin-dunne-repetitive-strain-injury-november-30\\\/\",\"url\":\"https:\\\/\\\/wormholeriders.net\\\/Drama\\\/category\\\/interviews\\\/2013-robin-dunne-repetitive-strain-injury-november-30\\\/\",\"name\":\"2013 - Robin Dunne Repetitive Strain Injury November 30 Archives - WormholeRiders Dedicated to Drama\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wormholeriders.net\\\/Drama\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wormholeriders.net\\\/Drama\\\/category\\\/interviews\\\/2013-robin-dunne-repetitive-strain-injury-november-30\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wormholeriders.net\\\/Drama\\\/category\\\/interviews\\\/2013-robin-dunne-repetitive-strain-injury-november-30\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wormholeriders.net\\\/Drama\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interviews\",\"item\":\"https:\\\/\\\/wormholeriders.net\\\/Drama\\\/category\\\/interviews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"2013 - Robin Dunne Repetitive Strain Injury November 30\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wormholeriders.net\\\/Drama\\\/#website\",\"url\":\"https:\\\/\\\/wormholeriders.net\\\/Drama\\\/\",\"name\":\"WormholeRiders Dedicated to Drama\",\"description\":\"This Is An Archive: Please visit wormholeriders.com\\\/blog\\\/\",\"publisher\":{\"@id\":\"https:\\\/\\\/wormholeriders.net\\\/Drama\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wormholeriders.net\\\/Drama\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wormholeriders.net\\\/Drama\\\/#organization\",\"name\":\"WormholeRiders Dedicated to Drama\",\"url\":\"https:\\\/\\\/wormholeriders.net\\\/Drama\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wormholeriders.net\\\/Drama\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wormholeriders.net\\\/Drama\\\/wp-content\\\/uploads\\\/2010\\\/09\\\/WormholeRiders-New-Logo-150.jpg\",\"contentUrl\":\"https:\\\/\\\/wormholeriders.net\\\/Drama\\\/wp-content\\\/uploads\\\/2010\\\/09\\\/WormholeRiders-New-Logo-150.jpg\",\"width\":\"150\",\"height\":\"150\",\"caption\":\"WormholeRiders Dedicated to Drama\"},\"image\":{\"@id\":\"https:\\\/\\\/wormholeriders.net\\\/Drama\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2013 - Robin Dunne Repetitive Strain Injury November 30 Archives - WormholeRiders Dedicated to Drama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wormholeriders.net\/Drama\/category\/interviews\/2013-robin-dunne-repetitive-strain-injury-november-30\/","og_locale":"en_US","og_type":"article","og_title":"2013 - Robin Dunne Repetitive Strain Injury November 30 Archives - WormholeRiders Dedicated to Drama","og_url":"https:\/\/wormholeriders.net\/Drama\/category\/interviews\/2013-robin-dunne-repetitive-strain-injury-november-30\/","og_site_name":"WormholeRiders Dedicated to Drama","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/wormholeriders.net\/Drama\/category\/interviews\/2013-robin-dunne-repetitive-strain-injury-november-30\/","url":"https:\/\/wormholeriders.net\/Drama\/category\/interviews\/2013-robin-dunne-repetitive-strain-injury-november-30\/","name":"2013 - Robin Dunne Repetitive Strain Injury November 30 Archives - WormholeRiders Dedicated to Drama","isPartOf":{"@id":"https:\/\/wormholeriders.net\/Drama\/#website"},"breadcrumb":{"@id":"https:\/\/wormholeriders.net\/Drama\/category\/interviews\/2013-robin-dunne-repetitive-strain-injury-november-30\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/wormholeriders.net\/Drama\/category\/interviews\/2013-robin-dunne-repetitive-strain-injury-november-30\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wormholeriders.net\/Drama\/"},{"@type":"ListItem","position":2,"name":"Interviews","item":"https:\/\/wormholeriders.net\/Drama\/category\/interviews\/"},{"@type":"ListItem","position":3,"name":"2013 - Robin Dunne Repetitive Strain Injury November 30"}]},{"@type":"WebSite","@id":"https:\/\/wormholeriders.net\/Drama\/#website","url":"https:\/\/wormholeriders.net\/Drama\/","name":"WormholeRiders Dedicated to Drama","description":"This Is An Archive: Please visit wormholeriders.com\/blog\/","publisher":{"@id":"https:\/\/wormholeriders.net\/Drama\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wormholeriders.net\/Drama\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/wormholeriders.net\/Drama\/#organization","name":"WormholeRiders Dedicated to Drama","url":"https:\/\/wormholeriders.net\/Drama\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wormholeriders.net\/Drama\/#\/schema\/logo\/image\/","url":"https:\/\/wormholeriders.net\/Drama\/wp-content\/uploads\/2010\/09\/WormholeRiders-New-Logo-150.jpg","contentUrl":"https:\/\/wormholeriders.net\/Drama\/wp-content\/uploads\/2010\/09\/WormholeRiders-New-Logo-150.jpg","width":"150","height":"150","caption":"WormholeRiders Dedicated to Drama"},"image":{"@id":"https:\/\/wormholeriders.net\/Drama\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/wormholeriders.net\/Drama\/wp-json\/wp\/v2\/categories\/712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wormholeriders.net\/Drama\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/wormholeriders.net\/Drama\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/wormholeriders.net\/Drama\/wp-json\/wp\/v2\/categories\/285"}],"wp:post_type":[{"href":"https:\/\/wormholeriders.net\/Drama\/wp-json\/wp\/v2\/posts?categories=712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}